{"id":1376,"date":"2018-02-17T08:26:28","date_gmt":"2018-02-17T07:26:28","guid":{"rendered":"http:\/\/svwolfersweiler.de\/blog\/?p=1376"},"modified":"2018-02-17T08:29:22","modified_gmt":"2018-02-17T07:29:22","slug":"und-weiter-gehts","status":"publish","type":"post","link":"https:\/\/svwolfersweiler.de\/blog\/blog\/2018\/02\/17\/und-weiter-gehts\/","title":{"rendered":"&#8230; und weiter geht&#8217;s"},"content":{"rendered":"<p><a href=\"https:\/\/svwolfersweiler.de\/blog\/wp-content\/uploads\/2018\/02\/Interesse_Desinteresse.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-1378\" src=\"https:\/\/svwolfersweiler.de\/blog\/wp-content\/uploads\/2018\/02\/Interesse_Desinteresse.jpg\" alt=\"\" width=\"228\" height=\"143\"><\/a>Auch das heutige Spiel gegen die SG Hoppst\u00e4dten-Weiersbach muss abgesagt. Stattdessen wird um 14 Uhr trainiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch das heutige Spiel gegen die SG Hoppst\u00e4dten-Weiersbach muss abgesagt. Stattdessen wird um 14 Uhr trainiert.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1376","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/1376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/comments?post=1376"}],"version-history":[{"count":3,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/1376\/revisions"}],"predecessor-version":[{"id":1380,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/1376\/revisions\/1380"}],"wp:attachment":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/media?parent=1376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/categories?post=1376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/tags?post=1376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}