{"id":1660,"date":"2018-10-11T08:47:36","date_gmt":"2018-10-11T07:47:36","guid":{"rendered":"http:\/\/svwolfersweiler.de\/blog\/?p=1660"},"modified":"2018-10-11T08:47:38","modified_gmt":"2018-10-11T07:47:38","slug":"kantersieg-gegen-titelaspiranten","status":"publish","type":"post","link":"https:\/\/svwolfersweiler.de\/blog\/blog\/2018\/10\/11\/kantersieg-gegen-titelaspiranten\/","title":{"rendered":"Kantersieg gegen Titelaspiranten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gegen den Titelaspiranten aus Scheuern\/-Steinbach-D\u00f6rsdorf hat unsere 1.Manschaft am vergangenen Wochenende einen 4:0 Kantersieg einfahren k\u00f6nnen. Personell wieder mit den Genesenen Patrick Schmidt, Michael Welker, David Zimmer und dem Urlauber Dennis Lauer deutlich besser besetzt, konnten wir vor allem in der 2. Halbzeit spielerisch die G\u00e4ste vor einige unl\u00f6sbare Aufgaben stellen.\u00a0 Ein auch in der H\u00f6he verdienter Heimsieg, der endlich mal wieder W\u00f6lfe mit Biss zeigen konnte und viele N\u00f6rgler und auch Selbstzweifler die Gewissheit brachte: Es geht doch !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gegen den Titelaspiranten aus Scheuern\/-Steinbach-D\u00f6rsdorf hat unsere 1.Manschaft am vergangenen Wochenende einen 4:0 Kantersieg einfahren k\u00f6nnen. Personell wieder mit den Genesenen Patrick Schmidt, Michael Welker, David Zimmer und dem Urlauber Dennis Lauer deutlich besser besetzt, konnten wir vor allem in der 2. Halbzeit spielerisch die G\u00e4ste vor einige unl\u00f6sbare Aufgaben stellen.\u00a0 Ein auch in der H\u00f6he verdienter Heimsieg, der endlich mal wieder W\u00f6lfe mit Biss zeigen konnte und viele N\u00f6rgler und auch Selbstzweifler die Gewissheit brachte: Es geht doch !<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1660","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/1660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/comments?post=1660"}],"version-history":[{"count":1,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/1660\/revisions"}],"predecessor-version":[{"id":1661,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/1660\/revisions\/1661"}],"wp:attachment":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/media?parent=1660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/categories?post=1660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/tags?post=1660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}