{"id":991,"date":"2017-04-19T07:00:29","date_gmt":"2017-04-19T06:00:29","guid":{"rendered":"http:\/\/svwolfersweiler.de\/blog\/?p=991"},"modified":"2017-04-19T07:00:29","modified_gmt":"2017-04-19T06:00:29","slug":"siege-in-steinberg-deckenhardt","status":"publish","type":"post","link":"https:\/\/svwolfersweiler.de\/blog\/blog\/2017\/04\/19\/siege-in-steinberg-deckenhardt\/","title":{"rendered":"Siege in Steinberg-Deckenhardt"},"content":{"rendered":"<p>Am vergangenen Samstag konnte wir zwei Siege in Steinberg-Deckenhardt einfahren. Unsere 1.Mannschaft siegte mit 2:0, unsere 2. Mannschaft konnte anschlie\u00dfend ebenfalls den Platz mit einem 3:1 Erfolg verlassen. F\u00fcr die 1.Mannschaft war das der gef\u00fchlte sichere Klassenerhalt, auch wenn es rechnerisch noch keine Sicherheit gibt, weil die Anzahl der m\u00f6glichen Absteiger auch noch offen ist. Auf den Drittletzten und kommenden Gegner Hirstein-Gehweiler haben wir mit 16 Punkten einen ausreichenden Abstand. Aufgrund der zuletzt doch besseren Spiele brauchen wir auch eigentlich nicht weiter nach unten zu schauen, sondern k\u00f6nnen uns das Ziel setzen, mindestens auf dem aktuell guten 7.Tabellenplatz die Saison abzuschlie\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am vergangenen Samstag konnte wir zwei Siege in Steinberg-Deckenhardt einfahren. Unsere 1.Mannschaft siegte mit 2:0, unsere 2. Mannschaft konnte anschlie\u00dfend ebenfalls den Platz mit einem 3:1 Erfolg verlassen. F\u00fcr die 1.Mannschaft war das der gef\u00fchlte sichere Klassenerhalt, auch wenn es rechnerisch noch keine Sicherheit gibt, weil die Anzahl der m\u00f6glichen Absteiger auch noch offen ist. Auf den Drittletzten und kommenden Gegner Hirstein-Gehweiler haben wir mit 16 Punkten einen ausreichenden Abstand. Aufgrund der zuletzt doch besseren Spiele brauchen wir auch eigentlich nicht weiter nach unten zu schauen, sondern k\u00f6nnen uns das Ziel setzen, mindestens auf dem aktuell guten 7.Tabellenplatz die Saison abzuschlie\u00dfen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-991","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/comments?post=991"}],"version-history":[{"count":1,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/991\/revisions"}],"predecessor-version":[{"id":992,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/posts\/991\/revisions\/992"}],"wp:attachment":[{"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/media?parent=991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/categories?post=991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svwolfersweiler.de\/blog\/wp-json\/wp\/v2\/tags?post=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}